{"id":2022,"date":"2025-07-03T21:33:01","date_gmt":"2025-07-03T21:33:01","guid":{"rendered":"https:\/\/munimarianodamasoberaun.gob.pe\/home\/?page_id=2022"},"modified":"2025-07-21T16:26:52","modified_gmt":"2025-07-21T16:26:52","slug":"tupa-catastro-1","status":"publish","type":"page","link":"https:\/\/munimarianodamasoberaun.gob.pe\/home\/tupa-catastro-1\/","title":{"rendered":"Catastro-1"},"content":{"rendered":"\n\n\n\n\n\n<h5><strong>Texto \u00danico de Procedimientos Administrativos &#8211; TUPA<\/strong><\/h5>\n\n<span style=\"background-color: rgb(0, 71, 178); color: rgb(255, 255, 255);\"><p style=\"text-align: center; background-color: rgb(0, 102, 204); color: rgb(255, 255, 255);\">Unidad de Planeamiento Urbano y Catastro<\/p><\/span><p style=\"text-align: center;\"><\/p>\n\n\n\n<p [object NamedNodeMap]><strong style=\"color: rgb(0, 0, 0);\">Consultas e Informes:<\/strong><\/p>\n\n\n\n\n\n\n\n\n<p style=\"color: rgb(68, 68, 68);\"><strong>BASE LEGAL:<\/strong><br><\/p><ul style=\"color: rgb(68, 68, 68);\"><li style=\"text-align: justify;\"><font size=\"2\">Ley N\u00ba 27972 &#8211; Ley Org\u00e1nica de Municipalidades del 26\/05\/2003.<\/font><\/li><li style=\"text-align: justify;\"><span style=\"font-size: small;\">Ley N\u00ba 29090 &#8211; Ley de Regulac. Habilit. Urbanas y de Edif. D.S. N\u00ba 008-2013-VIVIENDA. Reglamento de Ley 29090 y modificatorias.<\/span><\/li><\/ul><p style=\"text-align: justify;\"><\/p><p><\/p>\n\n\n<p style=\"color: rgb(68, 68, 68); font-size: small;\"><span style=\"font-size: medium;\"><strong>REQUISITOS:<\/strong><\/span><a href=\"https:\/\/drive.google.com\/file\/d\/1RBV66eHgI2yNvHLMKiOXz2Xr3kZ53XC_\/view?usp=sharing\"><br><\/a><\/p><ol style=\"font-size: small; color: rgb(68, 68, 68);\"><li style=\"text-align: justify;\"><a href=\"https:\/\/drive.google.com\/file\/d\/1RBV66eHgI2yNvHLMKiOXz2Xr3kZ53XC_\/view?usp=sharing\">Formulario \u00danico de Tr\u00e1mite (FUT)<\/a>. (Descargalo o solicitalo en mesa de partes)<\/li><li style=\"text-align: justify;\"><a href=\"CONTRATACION DE SUPERVISOR DE OBRA PARA EL PROYECTO:  &quot;CREACION DEL SERVICIO DE ESPACIOS PUBLICOS URBANOS EN EL PARQUE DEL CASERIO DE HONOLULO DISTRITO DE MARIANO DAMASO BERAUN DE LA PROVINCIA DE LEONCIO PRADO DEL DEPARTAMENTO DE HUANUCO&quot; CON CUI N 2649600.&quot; ****************************************************************** 1- AREA USUAREA:: GERENCIA DE DESARROLLO TERRITORIAL E INFRAESTRUCRURA:  2-FINALIDAD PUBLICA: El presente nace como resultado de una necesidad sentido y por iniciativa de la poblaci\u00f3n organizada de la zona de la localidad de Honolulu, Distrito de Mariano D\u00e1maso Beraun, Provincia de Leoncio Prado, Regi\u00f3n Hu\u00e1nuco.  Para poder contar con una infraestructura de servicios p\u00fablicos de integraci\u00f3n social y econ\u00f3mica en dicha localidad, En convenio con el programa LLANKASUM PERU, como responsable de la Unidad Ejecutora LA MUNICIPALIDAD DISTRITAL DE MARIANO DAMASO BERAUN, realizar\u00e1 la ejecuci\u00f3n del proyecto: &quot;CREACION DEL SERVICIOS DE ESPACIOS P\u00daBLICOS URBANOS EN EL PARQUE DEL CASER\u00cdO DE HONOLULO DISTRITO DE MARIANO DAMASO BERAUN DE LA PROVINCIA DE LEONCIO PRADO DEL DEPARTAMENTO DE HUANUCO&quot; CUI N\u00ba: 2649600, de ese modo generar empleo temporal a la poblaci\u00f3n m\u00e1s vulnerable.  3-OBJETIVO DE LA CONTRATACI\u00d3N: La contrataci\u00f3n de los servicios de un Ingeniero Supervisor de Obra, para verla directamente y permanente por la correcta ejecuci\u00f3n, t\u00e9cnica de la obra: &quot;CREACION DEL SERVICIOS DE ESPACIOS P\u00daBLICOS URBANOS EN EL PARQUE DEL CASER\u00cdO DE HONOLULO DISTRITO DE MARIANO DAMASO BERAUN DE LA PROVINCIA DE LEONCIO PRADO DEL DEPARTAMENTO DE HUANUCO&quot; CUI N\u00ba: 2649600.  4-DESCRIPCION DEL SERVICIO: FUNCIONES DEL SUPERVISOR Adicionalmente los servicios del Supervisor comprender\u00e1n lo siguiente: 1.Control T\u00e9cnico de la Ejecuci\u00f3n de la obra. 2.Control Econ\u00f3mico - Financiero. 3.Control Contractual - Administrativo. En el aspecto de detalle, a manera enumerativa m\u00e1s no limitativa, tenemos: FUNCIONES GENERALES 1.Iniciada la obra debe velar que esta se ejecute cumpliendo con el plazo previsto, el presupuesto asignado y la calidad especificada. 2.Asegurar el desarrollo normal de las actividades, verificando el cumplimiento de las metas, las normas y reglamentos vigentes, tanto en el aspecto t\u00e9cnico, legal administrativo, laborales y otros relacionados a los mismo. 3.Permanencia al 100% durante la ejecuci\u00f3n de la obra. 4.Establecer un sistema eficiente que permita controlar la calidad de los materiales o insumos utilizados en la obra, los procedimientos constructivos adoptados y calidad final de obra. 5.Control del aspecto Econ\u00f3mico - Financiero de la obra. 6.Emitir opini\u00f3n t\u00e9cnica oportuna y fundamentada, proponiendo soluciones a las eventuales consultas del Residente sobre diversos aspectos de la obra, en el plazo se\u00f1alado de acuerdo a la normatividad vigente. 7.Controlar el cumplimiento de las normas de seguridad, higiene y operatividad de la obra. 8.Controlar que el personal t\u00e9cnico y obrero que el ejecutor asigne a la obra, cuente con la capacidad, idoneidad y cantidad requeridas, 9.Controlar el avance de la obra y exigir al ejecutor que adopte las medidas correctivas, de ser el caso, para lograr su cumplimiento. 10.Verificar el cumplimiento, por parte del ejecutor, de las contribuciones, aporte a la seguridad social y beneficios sociales, relativos a la obra. 11.Controlar que la elaboraci\u00f3n de los planos de replanteo se realice de acuerdo al avance f\u00edsico de la obra. FUNCIONES ESPEC\u00cdFICAS: 1.Revisar permanentemente el Expediente T\u00e9cnico emitiendo informes que permitan que la Entidad, en caso necesario, adopte las eventuales medidas correctivas a fin de obtener una \u00f3ptima calidad de la obra mediante una adecuada ejecuci\u00f3n de los trabajos. 2.Velar directa y permanentemente, por la correcta ejecuci\u00f3n de la obra, a fin de que esta se ejecute en armon\u00eda y concordancia con las Resoluciones de la Contralor\u00eda N\u00aa 195-88-CG y 072-98-CG, Normas T\u00e9cnicas de Control, desde el inicio de la obra hasta la Liquidaci\u00f3n final de la misma. 3.Respetar el estudio (Expediente T\u00e9cnico) definitivo, el que solo podr\u00e1 ser modificado por autorizaci\u00f3n expresa de la Entidad, mediante la autorizaci\u00f3n administrativa pertinente. 4.Abrir el Cuaderno de Obra foliado, firmando todas sus p\u00e1ginas, conjuntamente con el Residente de la obra designado por la entidad ejecutora. 5.Anotar en el Cuaderno de Obra las ocurrencias, consultas y avances diarios de obra y reportar peri\u00f3dicamente del acumulado de dichas anotaciones a la Entidad. 6.Verificar y aprobar los trazos de obras parciales y\/o total; anotar las correspondientes autorizaciones en el cuaderno de obra. 7.Absolver las consultas hechas por el Residente en el Cuaderno de Obra, en el plazo m\u00e1ximo se\u00f1alado por el Reglamento; si la consulta fuese absuelta despu\u00e9s del plazo y afectar\u00e1 el plazo de ejecuci\u00f3n de la obra, esta ser\u00e1 responsabilidad del Supervisor. 8.Exigir a la Entidad Ejecutora, el retiro inmediato de cualquier subcontratista o trabajador, por incapacidad, incorrecci\u00f3n, desorden o cualquier otra falta que tenga relaci\u00f3n y afecte directamente a la correcta ejecuci\u00f3n de la obra. 9.Supervisar y controlar la entrega oportuna de los materiales, en las cantidades y en los plazos establecidos en el calendario de adquisici\u00f3n de materiales, as\u00ed mismo controlar la calidad de estos. Efectuar pruebas de control de calidad de materiales y ensayos de laboratorio requeridos en los procesos de ejecuci\u00f3n de la obra. 10.Ordenar el retiro inmediato de los materiales de mala calidad o que no correspondan a las especificaciones del Expediente T\u00e9cnico de obra. 11.Exigir al Residente la permanencia en obra, del personal y del equipo necesario para la ejecuci\u00f3n de la misma. 12.Revisar y visar las solicitudes del Residente para la adquisici\u00f3n de materiales, equipos y otros; controlando el ingreso de los mismos a la obra. 13.Verificar y valorizar los metrados de obra que presentara el Residente; elaborando la valorizaci\u00f3n, que son referenciales y deber\u00e1n refrendarse mediante las rendiciones de cuentas que realice el ejecutor. 14.Controlar por la vigencia de los plazos para ejecutar cada meta, informando oportunamente cuando estas deban ser reprogramadas en el caso de atraso. 15.Actualizar los Calendarios y Registros gr\u00e1ficos de la obra, mostrando en todo momento los datos parciales y acumulados de los avances y saldos pendientes de ejecuci\u00f3n. 16.Controlar el cumplimiento de los plazos parciales estipulados en el Calendario de Avance de obra Valorizado vigente, as\u00ed como el presupuesto anal\u00edtico. 17.Anotar en el Cuaderno de Obra, los atrasos injustificados exigiendo al ejecutor, la presentaci\u00f3n, cuando as\u00ed se requiera, del Calendario Acelerado, que ser\u00e1 aprobado por el Supervisor de obra, quien recomendar\u00e1 a la Entidad los atrasos de los plazos previstos. 18.Verificar que el Calendario de Avance de Obra Valorizado y actualizado por el ejecutor, se elabore en armon\u00eda con las pr\u00f3rrogas autorizadas. 19.Revisar, analizar, fundamentar y emitir opini\u00f3n con relaci\u00f3n a los presupuestos adicionales que el ejecutor pueda presentar, presentando el informe correspondiente con la documentaci\u00f3n sustentatoria que justifique y avale su procedencia. 20.Revisar, visar, y de ser el caso, emitir pronunciamiento sobre los planos de replanteo que deber\u00e1 presentar el ejecutor, as\u00ed como exigir su presentaci\u00f3n oportuna. 21.Controlar la utilizaci\u00f3n y prohibir el retiro de los materiales y\/o equipo de la obra por parte del ejecutor, en caso de resoluci\u00f3n de convenio de encargo y recibirlos previo inventario valorizado. 22.Informar sobre la solicitud de la recepci\u00f3n de obra presentada por el Residente, constando el estado real de los trabajos y certificado que la fecha precisada por el Residente es exacta en cuanto a la fecha de t\u00e9rmino de obra. 23.Ser\u00e1 miembro del comit\u00e9 de Recepci\u00f3n de Obra. 24. Revisar y visar la Memoria Descriptiva, Planos Post Construcci\u00f3n (replanteo), exigiendo su presentaci\u00f3n oportuna. 25.Velar porque el ejecutor presente en los plazos establecidos las rendiciones de cuentas documentadas y sustentadas de acuerdo a las directivas y normatividad vigente. 26.Autorizar cada uno de los Gastos a cuenta del presupuesto de obra.  5-LUGAR Y PLAZO DE EJECUCI\u00d3N: LUGAR:  Distrito \t: Mariano D\u00e1maso Beraun. Provincia\t: Leoncio Prado. Regi\u00f3n\t: Hu\u00e1nuco. Localidad\t: Honolulu PLAZO: el plazo de ejecuci\u00f3n del servicio es de 112 d\u00edas h\u00e1biles, contados desde el d\u00eda siguiente de notificada la orden de servicio o contrato.  6-ENTREGABLES: El servicio es especifico y temporal, y se realizar\u00e1 en 5 entregables; donde el residente de obra tiene que adjuntar los siguientes documentos: PRIMER ENTREGABLE Hasta los Treinta (38) d\u00edas h\u00e1biles, contados a partir del d\u00eda siguiente de notificada la orden de servicio o contrato -Informe de actividades desarrolladas. -Copia de la Aprobaci\u00f3n de la ETAPA de los requisitos previos por parte del programa Llankasum Per\u00fa.   SEGUNDO ENTREGABLE Hasta los Treinta (57) d\u00edas h\u00e1biles, contados a partir del d\u00eda siguiente de notificada la orden de servicio o contrato. -Informe mensual de actividades detalladas conforme al ITEM III. -Cuadro de Excel de la valorizaci\u00f3n mensual. -Resumen de valorizaci\u00f3n mensual. -Curva S de valorizaci\u00f3n mensual. -Panel fotogr\u00e1fico de la valorizaci\u00f3n mensual. TERCER ENTREGABLE Hasta los Treinta (78) d\u00edas h\u00e1biles, contados a partir del d\u00eda siguiente de notificada la orden de servicio o contrato. -Informe mensual de actividades detalladas conforme al ITEM III. -Cuadro de Excel de la valorizaci\u00f3n mensual. -Resumen de valorizaci\u00f3n mensual. -Curva S de valorizaci\u00f3n mensual. -Panel fotogr\u00e1fico de la valorizaci\u00f3n mensual.  CUARTO ENTREGABLE Hasta los Treinta (94) d\u00edas h\u00e1biles, contados a partir del d\u00eda siguiente de notificada la orden de servicio o contrato. -Informe mensual de actividades detalladas conforme al ITEM III. -Cuadro de Excel de la valorizaci\u00f3n mensual. -Resumen de valorizaci\u00f3n mensual. -Curva S de valorizaci\u00f3n mensual. -Panel fotogr\u00e1fico de la valorizaci\u00f3n mensual.  QUINTO ENTREGABLE Hasta los Treinta (112) d\u00edas h\u00e1biles, contados a partir del d\u00eda siguiente de notificada la orden de servicio o contrato. -Informe de actividades desarrolladas. -Copia de la Aprobaci\u00f3n de la ETAPA de RENDICION DE CUENTAS por parte del programa Llankasum Per\u00fa.   7-CONFORMIDAD: El pago procede con la aprobaci\u00f3n del \u00e1rea de la Gerencia de desarrollo territorial e infraestructura, encargado para dicho fin. En el caso que se encuentra alguna OBSERVACION, el supervisor tiene que levantar dichas observaciones.  8-FORMA Y CONDICIONES DE PAGO: Los pagos se realizar\u00e1n con la conformidad del GERENTE DE DESARROLLO TERRITORIAL E INFRAESTRUCTURA de acuerdo al siguiente detalle:  PAGO\tDESCRIPCI\u00d3N\tPLAZO DE PRESENTACI\u00d3N\tMONTO  PRIMER PAGO:    Informe respecto de las actividades descritas en el entregable N\u00b0 01, del presente documento\t  Hasta 38 d\u00edas h\u00e1biles, contados a partir del siguiente d\u00eda de recibida la Orden de Servicio o Contrato.\tS\/. 6,000.00  SEGUNDO PAGO :  Informe respecto de las actividades descritas en el entregable N\u00b0 02, del presente documento\tHasta 57 d\u00edas h\u00e1biles, contados a partir del siguiente d\u00eda de recibida la Orden de Servicio o Contrato.\t Conforme al porcentaje valorizado de obra.  TERCER PAGO :  Informe respecto de las actividades descritas en el entregable N\u00b0 03, del presente documento\t     Hasta 78 d\u00edas h\u00e1biles, contados a partir del siguiente d\u00eda de recibida la Orden de Servicio o Contrato.\t Conforme al porcentaje valorizado de obra.  CUARTO PAGO :  Informe respecto de las actividades descritas en el entregable N\u00b0 04, del presente documento\tHasta 94 d\u00edas h\u00e1biles, contados a partir del siguiente d\u00eda de recibida la Orden de Servicio o Contrato.\t Conforme al porcentaje valorizado de obra.  QUINTO PAGO :   Informe respecto de las actividades descritas en el entregable N\u00b0 05, del presente documento\tHasta 112 d\u00edas h\u00e1biles, contados a partir del siguiente d\u00eda de recibida la Orden de Servicio o Contrato.\tS\/. 3,000.00  9-PENALIDADES POR MORA:  Penalidad por Mora en la ejecuci\u00f3n de la prestaci\u00f3n: En caso de retraso injustificado del proveedor en la ejecuci\u00f3n de las prestaciones objeto del contrato, la Entidad le aplica autom\u00e1ticamente una penalidad por mora por cada d\u00eda de atraso. La penalidad se aplica autom\u00e1ticamente y se calcula de acuerdo a la siguiente f\u00f3rmula:  Penalidad diaria = 0.10 x monto                                F x plazo en d\u00edas  Donde F tiene los siguientes valores: a)\tPara plazos menores o iguales a sesenta (60) d\u00edas, para bienes, servicios en general, consultor\u00edas y ejecuci\u00f3n de obras: F = 0.40. b)\tPara plazos mayores a sesenta (60) d\u00edas: o\tPara bienes, servicios y consultor\u00edas: F = 0.25. o\tPara obras: F = 0.15. Tanto el monto como el plazo se refieren, seg\u00fan corresponda, a la ejecuci\u00f3n total del servicio o a la obligaci\u00f3n parcial, de ser el caso, que fuera materia de retraso. Se considera justificado el retraso, cuando el proveedor acredite, de modo objetivamente sustentado, que el mayor tiempo transcurrido no le resulta imputable. Esta calificaci\u00f3n del retraso como justificado no da lugar al pago de gastos generales de ning\u00fan tipo.   10-RESOLUCI\u00d3N CONTRACTUAL: La Entidad debe establecer las causales de soluci\u00f3n de contrato, as\u00ed como el procedimiento del mismo.\">Formulario \u00danico &#8211; FUHU<\/a>, debidamente suscrito por el solicitante y los profesionales responsables.<\/li><li style=\"text-align: justify;\">Copia literal de dominio, expedida por el registro de predios, en original y copia, con una anticipaci\u00f3n no mayor a 30 d\u00edas naturales.&nbsp;<\/li><li style=\"text-align: justify;\">Copia del autoavaluo vigente.<\/li><li style=\"text-align: justify;\">En el caso que el solicitante de la licencia de habilitaci\u00f3n urbana no sea el propietario del predio, deber\u00e1 presentar la documentaci\u00f3n que acredite que cuenta con derecho a subdividir y de ser el a edificar.<\/li><li style=\"text-align: justify;\">En el caso que el solicitante sea una persona jur\u00eddica, se acompa\u00f1ar\u00e1 vigencia de poder expedida por registros de personas jur\u00eddicas.<\/li><li style=\"text-align: justify;\">Documentaci\u00f3n t\u00e9cnica compuesta por:<br>* Plano de ubicaci\u00f3n y localizaci\u00f3n del lote materia de rectificaci\u00f3n de \u00e1rea.<br>* Plano matriz, perim\u00e9trico indicando medidas, \u00e1reas, linderos y colindantes del lote a rectificar.<br>* Memoria descriptiva indicando \u00e1reas, linderos y medidas perim\u00e9tricas del lote materia de rectificaci\u00f3n.<\/li><li style=\"text-align: justify;\">Pago por verificaci\u00f3n t\u00e9cnica. S\/.<\/li><li style=\"text-align: justify;\">Tasa administrativa. S\/.<\/li><li style=\"text-align: justify;\">Visaci\u00f3n de planos y memoria. S\/.<\/li><\/ol>\n<p style=\"color: rgb(68, 68, 68); font-size: small; text-align: justify;\"><em>Nota: Los documentos deben ser presentados en tres originales y dos en digital y suscritos por el solicitante y el profesional responsable del proyecto.<\/em><\/p><p><\/p>\n\n\n<p style=\"color: rgb(68, 68, 68); font-size: small; text-align: center;\"><span style=\"font-size: medium;\"><strong>COSTO:<\/strong><\/span><br><\/p><p style=\"text-align: center;\"><span style=\"text-align: justify; color: rgb(68, 68, 68); font-size: small;\">Gratuito<\/span><\/p><p><\/p>\n<p><br><\/p>\n<p><br><\/p>\n<p><br><\/p>\n<p><br><\/p>\n<p><br><\/p>\n<p><br><\/p>\n<p><br><\/p>\n<p><br><\/p>\n<p><br><\/p>\n<p style=\"color: rgb(68, 68, 68); font-size: small; text-align: center;\"><br><\/p><p style=\"text-align: center;\"><span style=\"text-align: justify; color: rgb(68, 68, 68); font-size: small;\">S\/. 36.00<\/span><\/p><p><\/p>\n<p style=\"color: rgb(68, 68, 68); font-size: small; text-align: center;\"><br><\/p><p style=\"text-align: center;\"><span style=\"text-align: justify; color: rgb(68, 68, 68); font-size: small;\">S\/. 80.00<\/span><\/p><p><\/p>\n<p style=\"color: rgb(68, 68, 68); font-size: small; text-align: center;\"><br><\/p><p style=\"text-align: center;\"><span style=\"text-align: justify; color: rgb(68, 68, 68); font-size: small;\">S\/. 105.00<\/span><\/p><p><\/p>\n\n\n\n\n\n\n\n\n<p style=\"color: rgb(68, 68, 68);\"><strong>BASE LEGAL:<\/strong><br><\/p><ul style=\"color: rgb(68, 68, 68);\"><li style=\"text-align: justify;\"><span style=\"font-size: small;\">Ley N\u00ba 29090 &#8211; Ley de Regulac. Habilit. Urbanas y de Edif. D.S. N\u00ba 008-2013-VIVIENDA. Reglamento de Ley 29090 y modificatorias.<\/span><br><\/li><li style=\"text-align: justify;\"><font size=\"2\">Ley N\u00ba 27972 &#8211; Ley Org\u00e1nica de Municipalidades del 26\/05\/2003.<\/font><\/li><li style=\"text-align: justify;\"><font size=\"2\">Ley N\u00ba 27444 (11.04.01) Ley del Procedimiento Administrativo, publicado el 11\/04\/2001.<\/font><\/li><li style=\"text-align: justify;\"><font size=\"2\">R.M. N\u00ba 10-93-JUS 23\/04\/93<\/font><\/li><\/ul><p style=\"text-align: justify;\"><\/p><p><\/p>\n\n\n<p style=\"color: rgb(68, 68, 68); font-size: small;\"><span style=\"font-size: medium;\"><strong>REQUISITOS:<\/strong><\/span><a href=\"https:\/\/drive.google.com\/file\/d\/1RBV66eHgI2yNvHLMKiOXz2Xr3kZ53XC_\/view?usp=sharing\"><br><\/a><\/p><ol style=\"font-size: small; color: rgb(68, 68, 68);\"><li style=\"text-align: justify;\"><a href=\"https:\/\/drive.google.com\/file\/d\/1RBV66eHgI2yNvHLMKiOXz2Xr3kZ53XC_\/view?usp=sharing\">Formulario \u00danico de Tr\u00e1mite (FUT)<\/a>. (Descargalo o solicitalo en mesa de partes)<\/li><li style=\"text-align: justify;\"><a href=\"CONTRATACION DE SUPERVISOR DE OBRA PARA EL PROYECTO:  &quot;CREACION DEL SERVICIO DE ESPACIOS PUBLICOS URBANOS EN EL PARQUE DEL CASERIO DE HONOLULO DISTRITO DE MARIANO DAMASO BERAUN DE LA PROVINCIA DE LEONCIO PRADO DEL DEPARTAMENTO DE HUANUCO&quot; CON CUI N 2649600.&quot; ****************************************************************** 1- AREA USUAREA:: GERENCIA DE DESARROLLO TERRITORIAL E INFRAESTRUCRURA:  2-FINALIDAD PUBLICA: El presente nace como resultado de una necesidad sentido y por iniciativa de la poblaci\u00f3n organizada de la zona de la localidad de Honolulu, Distrito de Mariano D\u00e1maso Beraun, Provincia de Leoncio Prado, Regi\u00f3n Hu\u00e1nuco.  Para poder contar con una infraestructura de servicios p\u00fablicos de integraci\u00f3n social y econ\u00f3mica en dicha localidad, En convenio con el programa LLANKASUM PERU, como responsable de la Unidad Ejecutora LA MUNICIPALIDAD DISTRITAL DE MARIANO DAMASO BERAUN, realizar\u00e1 la ejecuci\u00f3n del proyecto: &quot;CREACION DEL SERVICIOS DE ESPACIOS P\u00daBLICOS URBANOS EN EL PARQUE DEL CASER\u00cdO DE HONOLULO DISTRITO DE MARIANO DAMASO BERAUN DE LA PROVINCIA DE LEONCIO PRADO DEL DEPARTAMENTO DE HUANUCO&quot; CUI N\u00ba: 2649600, de ese modo generar empleo temporal a la poblaci\u00f3n m\u00e1s vulnerable.  3-OBJETIVO DE LA CONTRATACI\u00d3N: La contrataci\u00f3n de los servicios de un Ingeniero Supervisor de Obra, para verla directamente y permanente por la correcta ejecuci\u00f3n, t\u00e9cnica de la obra: &quot;CREACION DEL SERVICIOS DE ESPACIOS P\u00daBLICOS URBANOS EN EL PARQUE DEL CASER\u00cdO DE HONOLULO DISTRITO DE MARIANO DAMASO BERAUN DE LA PROVINCIA DE LEONCIO PRADO DEL DEPARTAMENTO DE HUANUCO&quot; CUI N\u00ba: 2649600.  4-DESCRIPCION DEL SERVICIO: FUNCIONES DEL SUPERVISOR Adicionalmente los servicios del Supervisor comprender\u00e1n lo siguiente: 1.Control T\u00e9cnico de la Ejecuci\u00f3n de la obra. 2.Control Econ\u00f3mico - Financiero. 3.Control Contractual - Administrativo. En el aspecto de detalle, a manera enumerativa m\u00e1s no limitativa, tenemos: FUNCIONES GENERALES 1.Iniciada la obra debe velar que esta se ejecute cumpliendo con el plazo previsto, el presupuesto asignado y la calidad especificada. 2.Asegurar el desarrollo normal de las actividades, verificando el cumplimiento de las metas, las normas y reglamentos vigentes, tanto en el aspecto t\u00e9cnico, legal administrativo, laborales y otros relacionados a los mismo. 3.Permanencia al 100% durante la ejecuci\u00f3n de la obra. 4.Establecer un sistema eficiente que permita controlar la calidad de los materiales o insumos utilizados en la obra, los procedimientos constructivos adoptados y calidad final de obra. 5.Control del aspecto Econ\u00f3mico - Financiero de la obra. 6.Emitir opini\u00f3n t\u00e9cnica oportuna y fundamentada, proponiendo soluciones a las eventuales consultas del Residente sobre diversos aspectos de la obra, en el plazo se\u00f1alado de acuerdo a la normatividad vigente. 7.Controlar el cumplimiento de las normas de seguridad, higiene y operatividad de la obra. 8.Controlar que el personal t\u00e9cnico y obrero que el ejecutor asigne a la obra, cuente con la capacidad, idoneidad y cantidad requeridas, 9.Controlar el avance de la obra y exigir al ejecutor que adopte las medidas correctivas, de ser el caso, para lograr su cumplimiento. 10.Verificar el cumplimiento, por parte del ejecutor, de las contribuciones, aporte a la seguridad social y beneficios sociales, relativos a la obra. 11.Controlar que la elaboraci\u00f3n de los planos de replanteo se realice de acuerdo al avance f\u00edsico de la obra. FUNCIONES ESPEC\u00cdFICAS: 1.Revisar permanentemente el Expediente T\u00e9cnico emitiendo informes que permitan que la Entidad, en caso necesario, adopte las eventuales medidas correctivas a fin de obtener una \u00f3ptima calidad de la obra mediante una adecuada ejecuci\u00f3n de los trabajos. 2.Velar directa y permanentemente, por la correcta ejecuci\u00f3n de la obra, a fin de que esta se ejecute en armon\u00eda y concordancia con las Resoluciones de la Contralor\u00eda N\u00aa 195-88-CG y 072-98-CG, Normas T\u00e9cnicas de Control, desde el inicio de la obra hasta la Liquidaci\u00f3n final de la misma. 3.Respetar el estudio (Expediente T\u00e9cnico) definitivo, el que solo podr\u00e1 ser modificado por autorizaci\u00f3n expresa de la Entidad, mediante la autorizaci\u00f3n administrativa pertinente. 4.Abrir el Cuaderno de Obra foliado, firmando todas sus p\u00e1ginas, conjuntamente con el Residente de la obra designado por la entidad ejecutora. 5.Anotar en el Cuaderno de Obra las ocurrencias, consultas y avances diarios de obra y reportar peri\u00f3dicamente del acumulado de dichas anotaciones a la Entidad. 6.Verificar y aprobar los trazos de obras parciales y\/o total; anotar las correspondientes autorizaciones en el cuaderno de obra. 7.Absolver las consultas hechas por el Residente en el Cuaderno de Obra, en el plazo m\u00e1ximo se\u00f1alado por el Reglamento; si la consulta fuese absuelta despu\u00e9s del plazo y afectar\u00e1 el plazo de ejecuci\u00f3n de la obra, esta ser\u00e1 responsabilidad del Supervisor. 8.Exigir a la Entidad Ejecutora, el retiro inmediato de cualquier subcontratista o trabajador, por incapacidad, incorrecci\u00f3n, desorden o cualquier otra falta que tenga relaci\u00f3n y afecte directamente a la correcta ejecuci\u00f3n de la obra. 9.Supervisar y controlar la entrega oportuna de los materiales, en las cantidades y en los plazos establecidos en el calendario de adquisici\u00f3n de materiales, as\u00ed mismo controlar la calidad de estos. Efectuar pruebas de control de calidad de materiales y ensayos de laboratorio requeridos en los procesos de ejecuci\u00f3n de la obra. 10.Ordenar el retiro inmediato de los materiales de mala calidad o que no correspondan a las especificaciones del Expediente T\u00e9cnico de obra. 11.Exigir al Residente la permanencia en obra, del personal y del equipo necesario para la ejecuci\u00f3n de la misma. 12.Revisar y visar las solicitudes del Residente para la adquisici\u00f3n de materiales, equipos y otros; controlando el ingreso de los mismos a la obra. 13.Verificar y valorizar los metrados de obra que presentara el Residente; elaborando la valorizaci\u00f3n, que son referenciales y deber\u00e1n refrendarse mediante las rendiciones de cuentas que realice el ejecutor. 14.Controlar por la vigencia de los plazos para ejecutar cada meta, informando oportunamente cuando estas deban ser reprogramadas en el caso de atraso. 15.Actualizar los Calendarios y Registros gr\u00e1ficos de la obra, mostrando en todo momento los datos parciales y acumulados de los avances y saldos pendientes de ejecuci\u00f3n. 16.Controlar el cumplimiento de los plazos parciales estipulados en el Calendario de Avance de obra Valorizado vigente, as\u00ed como el presupuesto anal\u00edtico. 17.Anotar en el Cuaderno de Obra, los atrasos injustificados exigiendo al ejecutor, la presentaci\u00f3n, cuando as\u00ed se requiera, del Calendario Acelerado, que ser\u00e1 aprobado por el Supervisor de obra, quien recomendar\u00e1 a la Entidad los atrasos de los plazos previstos. 18.Verificar que el Calendario de Avance de Obra Valorizado y actualizado por el ejecutor, se elabore en armon\u00eda con las pr\u00f3rrogas autorizadas. 19.Revisar, analizar, fundamentar y emitir opini\u00f3n con relaci\u00f3n a los presupuestos adicionales que el ejecutor pueda presentar, presentando el informe correspondiente con la documentaci\u00f3n sustentatoria que justifique y avale su procedencia. 20.Revisar, visar, y de ser el caso, emitir pronunciamiento sobre los planos de replanteo que deber\u00e1 presentar el ejecutor, as\u00ed como exigir su presentaci\u00f3n oportuna. 21.Controlar la utilizaci\u00f3n y prohibir el retiro de los materiales y\/o equipo de la obra por parte del ejecutor, en caso de resoluci\u00f3n de convenio de encargo y recibirlos previo inventario valorizado. 22.Informar sobre la solicitud de la recepci\u00f3n de obra presentada por el Residente, constando el estado real de los trabajos y certificado que la fecha precisada por el Residente es exacta en cuanto a la fecha de t\u00e9rmino de obra. 23.Ser\u00e1 miembro del comit\u00e9 de Recepci\u00f3n de Obra. 24. Revisar y visar la Memoria Descriptiva, Planos Post Construcci\u00f3n (replanteo), exigiendo su presentaci\u00f3n oportuna. 25.Velar porque el ejecutor presente en los plazos establecidos las rendiciones de cuentas documentadas y sustentadas de acuerdo a las directivas y normatividad vigente. 26.Autorizar cada uno de los Gastos a cuenta del presupuesto de obra.  5-LUGAR Y PLAZO DE EJECUCI\u00d3N: LUGAR:  Distrito \t: Mariano D\u00e1maso Beraun. Provincia\t: Leoncio Prado. Regi\u00f3n\t: Hu\u00e1nuco. Localidad\t: Honolulu PLAZO: el plazo de ejecuci\u00f3n del servicio es de 112 d\u00edas h\u00e1biles, contados desde el d\u00eda siguiente de notificada la orden de servicio o contrato.  6-ENTREGABLES: El servicio es especifico y temporal, y se realizar\u00e1 en 5 entregables; donde el residente de obra tiene que adjuntar los siguientes documentos: PRIMER ENTREGABLE Hasta los Treinta (38) d\u00edas h\u00e1biles, contados a partir del d\u00eda siguiente de notificada la orden de servicio o contrato -Informe de actividades desarrolladas. -Copia de la Aprobaci\u00f3n de la ETAPA de los requisitos previos por parte del programa Llankasum Per\u00fa.   SEGUNDO ENTREGABLE Hasta los Treinta (57) d\u00edas h\u00e1biles, contados a partir del d\u00eda siguiente de notificada la orden de servicio o contrato. -Informe mensual de actividades detalladas conforme al ITEM III. -Cuadro de Excel de la valorizaci\u00f3n mensual. -Resumen de valorizaci\u00f3n mensual. -Curva S de valorizaci\u00f3n mensual. -Panel fotogr\u00e1fico de la valorizaci\u00f3n mensual. TERCER ENTREGABLE Hasta los Treinta (78) d\u00edas h\u00e1biles, contados a partir del d\u00eda siguiente de notificada la orden de servicio o contrato. -Informe mensual de actividades detalladas conforme al ITEM III. -Cuadro de Excel de la valorizaci\u00f3n mensual. -Resumen de valorizaci\u00f3n mensual. -Curva S de valorizaci\u00f3n mensual. -Panel fotogr\u00e1fico de la valorizaci\u00f3n mensual.  CUARTO ENTREGABLE Hasta los Treinta (94) d\u00edas h\u00e1biles, contados a partir del d\u00eda siguiente de notificada la orden de servicio o contrato. -Informe mensual de actividades detalladas conforme al ITEM III. -Cuadro de Excel de la valorizaci\u00f3n mensual. -Resumen de valorizaci\u00f3n mensual. -Curva S de valorizaci\u00f3n mensual. -Panel fotogr\u00e1fico de la valorizaci\u00f3n mensual.  QUINTO ENTREGABLE Hasta los Treinta (112) d\u00edas h\u00e1biles, contados a partir del d\u00eda siguiente de notificada la orden de servicio o contrato. -Informe de actividades desarrolladas. -Copia de la Aprobaci\u00f3n de la ETAPA de RENDICION DE CUENTAS por parte del programa Llankasum Per\u00fa.   7-CONFORMIDAD: El pago procede con la aprobaci\u00f3n del \u00e1rea de la Gerencia de desarrollo territorial e infraestructura, encargado para dicho fin. En el caso que se encuentra alguna OBSERVACION, el supervisor tiene que levantar dichas observaciones.  8-FORMA Y CONDICIONES DE PAGO: Los pagos se realizar\u00e1n con la conformidad del GERENTE DE DESARROLLO TERRITORIAL E INFRAESTRUCTURA de acuerdo al siguiente detalle:  PAGO\tDESCRIPCI\u00d3N\tPLAZO DE PRESENTACI\u00d3N\tMONTO  PRIMER PAGO:    Informe respecto de las actividades descritas en el entregable N\u00b0 01, del presente documento\t  Hasta 38 d\u00edas h\u00e1biles, contados a partir del siguiente d\u00eda de recibida la Orden de Servicio o Contrato.\tS\/. 6,000.00  SEGUNDO PAGO :  Informe respecto de las actividades descritas en el entregable N\u00b0 02, del presente documento\tHasta 57 d\u00edas h\u00e1biles, contados a partir del siguiente d\u00eda de recibida la Orden de Servicio o Contrato.\t Conforme al porcentaje valorizado de obra.  TERCER PAGO :  Informe respecto de las actividades descritas en el entregable N\u00b0 03, del presente documento\t     Hasta 78 d\u00edas h\u00e1biles, contados a partir del siguiente d\u00eda de recibida la Orden de Servicio o Contrato.\t Conforme al porcentaje valorizado de obra.  CUARTO PAGO :  Informe respecto de las actividades descritas en el entregable N\u00b0 04, del presente documento\tHasta 94 d\u00edas h\u00e1biles, contados a partir del siguiente d\u00eda de recibida la Orden de Servicio o Contrato.\t Conforme al porcentaje valorizado de obra.  QUINTO PAGO :   Informe respecto de las actividades descritas en el entregable N\u00b0 05, del presente documento\tHasta 112 d\u00edas h\u00e1biles, contados a partir del siguiente d\u00eda de recibida la Orden de Servicio o Contrato.\tS\/. 3,000.00  9-PENALIDADES POR MORA:  Penalidad por Mora en la ejecuci\u00f3n de la prestaci\u00f3n: En caso de retraso injustificado del proveedor en la ejecuci\u00f3n de las prestaciones objeto del contrato, la Entidad le aplica autom\u00e1ticamente una penalidad por mora por cada d\u00eda de atraso. La penalidad se aplica autom\u00e1ticamente y se calcula de acuerdo a la siguiente f\u00f3rmula:  Penalidad diaria = 0.10 x monto                                F x plazo en d\u00edas  Donde F tiene los siguientes valores: a)\tPara plazos menores o iguales a sesenta (60) d\u00edas, para bienes, servicios en general, consultor\u00edas y ejecuci\u00f3n de obras: F = 0.40. b)\tPara plazos mayores a sesenta (60) d\u00edas: o\tPara bienes, servicios y consultor\u00edas: F = 0.25. o\tPara obras: F = 0.15. Tanto el monto como el plazo se refieren, seg\u00fan corresponda, a la ejecuci\u00f3n total del servicio o a la obligaci\u00f3n parcial, de ser el caso, que fuera materia de retraso. Se considera justificado el retraso, cuando el proveedor acredite, de modo objetivamente sustentado, que el mayor tiempo transcurrido no le resulta imputable. Esta calificaci\u00f3n del retraso como justificado no da lugar al pago de gastos generales de ning\u00fan tipo.   10-RESOLUCI\u00d3N CONTRACTUAL: La Entidad debe establecer las causales de soluci\u00f3n de contrato, as\u00ed como el procedimiento del mismo.\">Formulario \u00danico &#8211; FUHU<\/a>, por triplicado debidamente suscrito.<\/li><li style=\"text-align: justify;\">Copia literal de dominio, expedida por el registro de predios, en original y copia, con una anticipaci\u00f3n no mayor a 30 d\u00edas naturales.&nbsp;<\/li><li style=\"text-align: justify;\">Copia de autoavaluo vigente.<\/li><li style=\"text-align: justify;\">En el caso que el solicitante no sea el propietario del predio, adem\u00e1s deber\u00e1 presentar la documentaci\u00f3n que acredite que cuenta con derecho a habilitar y de ser el caso, a edificar (por duplicado).<\/li><li style=\"text-align: justify;\">En el caso que el solicitante sea una persona jur\u00eddica, se acompa\u00f1ar\u00e1 vigencia de poder expedida por el registro de personas jur\u00eddicas.<\/li><li style=\"text-align: justify;\">Declaraci\u00f3n Jurada de habilitaci\u00f3n de los profesionales que intervienen en el proyecto de encontrarse h\u00e1biles para suscribir la documentaci\u00f3n t\u00e9cnica (por duplicado).<\/li><li style=\"text-align: justify;\">Anexo E: Independizaci\u00f3n de terreno rustico \/ habilitaci\u00f3n urbana.<\/li><li style=\"text-align: justify;\">Declaraci\u00f3n jurada de inexistencia de feudatarios.<\/li><li style=\"text-align: justify;\">Documentaci\u00f3n t\u00e9cnica (por triplicado) compuesta por:<br>* Plano de ubicaci\u00f3n y localizaci\u00f3n del terreno matriz, con coordenadas UTM.<br>* Plano de planeamiento integral con la propuesta de integraci\u00f3n a la trama urbana m\u00e1s cercana, se\u00f1alando el per\u00edmetro y el relieve con curvas de nivel, usos de suelos aportes normativos, georeferenciados a la red geod\u00e9sica nacional, referida al datum oficial, en concordancia con el plan de desarrollo urb. aprobado por la municipalidad provincial de ser el caso.<br>* Plano de predio r\u00fastico matriz, indicando per\u00edmetro, linderos, \u00e1rea, curvas de nivel y nomenclatura original, georeferenciadas a la red geod\u00e9sica nacional, refererida al datum oficial.<br>* Plano de independizaci\u00f3n, se\u00f1alando la parcela independizada y la parcela remanente, indicando per\u00edmetro, linderos, \u00e1rea, curvas de nivel y nomenclatura original, georeferenciados a la red geod\u00e9sica nacional, referida al datum oficial. Cuando corresponda, el plano de parcelaci\u00f3n indentificar\u00e1 el n\u00famero de parcelas con los sufijos del previo matriz.<br>* Memoria descriptiva indicando \u00e1reas, linderos y medidas perim\u00e9tricas del predio matriz de la porci\u00f3n independizada y el remanente.<\/li><li style=\"text-align: justify;\">Certif. de inexist. de restos arqueol\u00f3gicos, en aquellos casos en que el per\u00edmetro de \u00e1rea a habilitar se superponga con un \u00e1rea previamente declarada como parte integrante del patrimonio cultural de la naci\u00f3n.<\/li><li style=\"text-align: justify;\">Pago por verificaci\u00f3n t\u00e9cnica. S\/.<\/li><li style=\"text-align: justify;\">Tasa administrativa. S\/.<\/li><li style=\"text-align: justify;\">Visaci\u00f3n de planos y memoria. S\/.<\/li><\/ol>\n<p style=\"color: rgb(68, 68, 68); font-size: small; text-align: justify;\"><em>Nota: La independizaci\u00f3n de predios r\u00fasticos y la habilitaci\u00f3n urb. pueden realizarse en un solo procedimiento, en este caso la comisi\u00f3n t\u00e9cnica verificar\u00e1 procedimientos simultaneamente.<\/em><\/p><p><\/p>\n\n\n<p style=\"color: rgb(68, 68, 68); font-size: small; text-align: center;\"><span style=\"font-size: medium;\"><strong>COSTO:<\/strong><\/span><br><\/p><p style=\"text-align: center;\"><span style=\"text-align: justify; color: rgb(68, 68, 68); font-size: small;\">Gratuito<\/span><\/p><p><\/p>\n<p style=\"text-align: center;\"><span style=\"color:#444444;\"><span style=\"font-size:small;\">M\u00e1ximo 1 UIT<\/span><\/span><\/p>\n<p><br><\/p>\n<p><br><\/p>\n<p><br><\/p>\n<p><br><\/p>\n<p><br><\/p>\n<p><br><\/p>\n<p><br><\/p>\n<p><br><\/p>\n<p><br><\/p>\n<p><br><\/p>\n<p><br><\/p>\n<p><br><\/p>\n<p><br><\/p>\n<p><br><\/p>\n<p><br><\/p>\n<p><br><\/p>\n<p><br><\/p>\n<p><br><\/p>\n<p><br><\/p>\n<p><br><\/p>\n<p><br><\/p>\n<p><br><\/p>\n<p style=\"color: rgb(68, 68, 68); font-size: small; text-align: center;\"><br><\/p><p style=\"text-align: center;\"><span style=\"text-align: justify; color: rgb(68, 68, 68); font-size: small;\">S\/. 36.00<\/span><\/p><p><\/p>\n<p style=\"color: rgb(68, 68, 68); font-size: small; text-align: center;\"><br><\/p><p style=\"text-align: center;\"><span style=\"text-align: justify; color: rgb(68, 68, 68); font-size: small;\">S\/. 80.00<\/span><\/p><p><\/p>\n<p style=\"color: rgb(68, 68, 68); font-size: small; text-align: center;\"><br><\/p><p style=\"text-align: center;\"><span style=\"text-align: justify; color: rgb(68, 68, 68); font-size: small;\">S\/. 105.00<\/span><\/p><p><\/p>\n\n\n\n\n\n\n\n\n<p style=\"color: rgb(68, 68, 68); text-align: justify;\"><strong>Modalidad A: Aprobaci\u00f3n autom\u00e1tica.<\/strong><br><br><strong>Modalidad B: Aprobaci\u00f3n autom\u00e1tica con firmas de profesionales responsables.<\/strong><strong><font size=\"2\"><br><br><\/font>BASE LEGAL:<\/strong><\/p><ul style=\"color: rgb(68, 68, 68);\"><li style=\"text-align: justify;\"><font size=\"2\">Ley N\u00ba 27972 &#8211; Ley Org\u00e1nica de Municipalidades.<\/font><\/li><li style=\"text-align: justify;\"><span style=\"font-size: small;\">Ley N\u00ba 29090 &#8211; Ley de Regulaci\u00f3n de&nbsp; Habilit. Urbanas y de Edificac. D.S. N\u00ba 024-2008-VIVIENDA. Reglamento de Ley 29090.<\/span><\/li><\/ul>\n\n\n<p style=\"color: rgb(68, 68, 68); font-size: small;\"><span style=\"font-size: medium;\"><strong>REQUISITOS<\/strong><\/span><a href=\"https:\/\/drive.google.com\/file\/d\/1RBV66eHgI2yNvHLMKiOXz2Xr3kZ53XC_\/view?usp=sharing\"><br><\/a><\/p><ol style=\"font-size: small; color: rgb(68, 68, 68);\"><li style=\"text-align: justify;\"><a href=\"https:\/\/drive.google.com\/file\/d\/1RBV66eHgI2yNvHLMKiOXz2Xr3kZ53XC_\/view?usp=sharing\">Formulario \u00danico de Tr\u00e1mite (FUT)<\/a>. (Descargalo o solicitalo en mesa de partes)<\/li><li style=\"text-align: justify;\"><a href=\"https:\/\/drive.google.com\/file\/d\/1LC_xO5n2h1Zp2mo1TII6d3pe0ghzV1K6\/view?usp=sharing\">Formulario \u00danico de Edificaciones &#8211; FUE<\/a>, consignando los datos requeridos.<\/li><li style=\"text-align: justify;\">Copia literal de dominio, expedida por el registro de predios, con una antiguedad no mayor a treinta d\u00edas naturales.<\/li><li style=\"text-align: justify;\">Copia de autoavaluo vigente.<\/li><li style=\"text-align: justify;\">En el caso que el solicitante de la licencia de edific. no sea el propietario del predio, se deber\u00e1 presentar adem\u00e1s la documentaci\u00f3n que acredite que cuenta con derecho a edificar.<\/li><li style=\"text-align: justify;\">Si el solicitante es una persona jur\u00eddica, se acompa\u00f1ar\u00e1 vigencia de poder expedida por el registro de personas jur\u00eddicas con una vigencia no mayor a treinta (30) d\u00edas naturales.<\/li><li style=\"text-align: justify;\">Plano de ubicaci\u00f3n y plano de la obra a ejecutar. En el caso de ampliaci\u00f3n, remodelaciones de inmuebles, que cuenten con licencia&nbsp; o declaratoria de f\u00e1brica, el plano de planta se desarrollar\u00e1 sobre copia del plano de la edificaci\u00f3n existente, con indicaci\u00f3n de las obras nuevas a edificarse. El plano de planta se desarrollar\u00e1 sobre copia de plano de la edificaci\u00f3n existente, con indicaci\u00f3n de las obras nuevas a edificarse.&nbsp;<\/li><li style=\"text-align: justify;\">En el FUT deber\u00e1 constar el sello de pago de la autoliquidaci\u00f3n.<\/li><li style=\"text-align: justify;\">Pago por inspecci\u00f3n t\u00e9cnica. S\/.<\/li><li style=\"text-align: justify;\">Tasa administrativa. S\/.<\/li><li style=\"text-align: justify;\">Derecho de licencia.<br><strong><br>Solo para los siguientes casos, los requisitos adicionales a presentar ser\u00e1n:<\/strong><br><strong>a)<\/strong> Para vivienda unifamiliar de hasta 120 m2 construidos y siempre que sean&nbsp; la \u00fanica edificaci\u00f3n que constituya en el lote, se podr\u00e1 optar por la adquisici\u00f3n, planos de banco de proyectos de la Municipalidad.<br>a-1 Planos de arquitectura firmados por un arquitecto colegiado.<br>a-2 Planos de estructuras elaborados y firmados por ingeniero civil colegiado.<br>a-3 Carta de responsabilidad de obra seg\u00fan formato.<br><strong>b) <\/strong>Para ampliaci\u00f3n de vivienda unifamiliar, cuya edificaci\u00f3n original cuente con la licencia de obra y declaratoria de f\u00e1brica, el requisito es igual que en el inciaso a).<br><strong>c) <\/strong>Para la demolici\u00f3n total de edificaciones, siempre que no constituyan parte integrante del patrimonio cultutal de la naci\u00f3n y donde se utilizan los explosivos, presentar\u00e1n:<br>a.2 Planos de estructuras elaborados y firmados por ingeniero civil colegiado.<br>a.3 Carta de responsabilidad de obra seg\u00fan formato.<br><br><strong>Pueden acogerse a esta modalidad:<br>a.&nbsp;<\/strong>&nbsp;La remodelaci\u00f3n de una edificaci\u00f3n, sin modificaci\u00f3n estructural ni aumento de \u00e1rea construida.<br><strong>b. <\/strong>La construcci\u00f3n de cercos de m\u00e1s de 20m hasta 1000m de longitud.<br><strong>c. <\/strong>Las obras menores, seg\u00fan lo establecido en el Reglamento Nacional de Edificaciones.<br><strong>d. <\/strong>Las obras de car\u00e1cter militar de las Fuerzas Armadas y las de la Policia Nacional del Per\u00fa, as\u00ed como los establecimientos de reclusi\u00f3n penal, los que deber\u00e1n ejecutarse con sujeci\u00f3n a las pol\u00edticas de acondicionamiento territorial y desarrollo urbano.<\/li><\/ol>\n\n\n<p style=\"color: rgb(68, 68, 68); font-size: small; text-align: center;\"><span style=\"font-size: medium;\"><strong>COSTO:<\/strong><\/span><br><\/p><p style=\"text-align: center;\"><span style=\"text-align: justify; color: rgb(68, 68, 68); font-size: small;\">Gratuito<\/span><\/p><p><\/p>\n<p style=\"color: rgb(68, 68, 68); font-size: small; text-align: center;\"><span style=\"text-align: justify;\">S\/. 37.72<\/span><br><\/p><p><\/p>\n<p style=\"color: rgb(68, 68, 68); font-size: small; text-align: center;\"><span style=\"text-align: justify;\">S\/. 56.60<\/span><br><\/p><p><\/p>\n<p style=\"color: rgb(68, 68, 68); font-size: small; text-align: center;\"><span style=\"text-align: justify;\">S\/. 244.10<\/span><br><\/p><p><\/p>\n\n\n\n\n\n\n\n\n<p style=\"color: rgb(68, 68, 68); text-align: justify;\"><strong>BASE LEGAL:<\/strong><\/p><ul style=\"color: rgb(68, 68, 68);\"><li style=\"text-align: justify;\"><font size=\"2\">Ley N\u00ba 27972 &#8211; Ley Org\u00e1nica de Municipalidades.<\/font><\/li><li style=\"text-align: justify;\"><span style=\"font-size: small;\">Ley N\u00ba 29090 &#8211; Ley de Regulaci\u00f3n de&nbsp; Habilitaciones Urbanas y de Edificaciones.<\/span><\/li><li style=\"text-align: justify;\"><span style=\"font-size: small;\">D.S. N\u00ba 024-2008-VIVIENDA. Reglamento de Ley 29090.<\/span><\/li><\/ul>\n\n\n<p style=\"color: rgb(68, 68, 68); font-size: small;\"><span style=\"font-size: medium;\"><strong>REQUISITOS:<\/strong><\/span><a href=\"https:\/\/drive.google.com\/file\/d\/1RBV66eHgI2yNvHLMKiOXz2Xr3kZ53XC_\/view?usp=sharing\"><br><\/a><\/p><ol style=\"font-size: small; color: rgb(68, 68, 68);\"><li style=\"text-align: justify;\"><a href=\"https:\/\/drive.google.com\/file\/d\/1RBV66eHgI2yNvHLMKiOXz2Xr3kZ53XC_\/view?usp=sharing\">Formulario \u00danico de Tr\u00e1mite (FUT)<\/a>. (Descargalo o solicitalo en mesa de partes)<\/li><li style=\"text-align: justify;\"><a href=\"https:\/\/drive.google.com\/file\/d\/1LC_xO5n2h1Zp2mo1TII6d3pe0ghzV1K6\/view?usp=sharing\">Formulario \u00danico de Edificaciones &#8211; FUE<\/a>, consignando los datos requeridos.<\/li><li style=\"text-align: justify;\">Copia literal de dominio, expedida por el registro de predios, con una anticipaci\u00f3n no mayor a 30 d\u00edas naturales.<\/li><li style=\"text-align: justify;\">Copia de autoavaluo vigente.<\/li><li style=\"text-align: justify;\">En el caso que el solicitante no sea el propietario del predio, se deber\u00e1 presentar adem\u00e1s la documentaci\u00f3n que acredite dicho derecho.<\/li><li style=\"text-align: justify;\">Si el solicitante es una persona jur\u00eddica, se acompa\u00f1ar\u00e1 vigencia de poder expedida por el registros p\u00fablicos con una anticipaci\u00f3n no mayor a treinta (30) d\u00edas naturales.<\/li><li style=\"text-align: justify;\">Constancia de habilitaci\u00f3n de los profesionales que suscriben la documentaci\u00f3n t\u00e9cnica.<\/li><li style=\"text-align: justify;\">Documentaci\u00f3n t\u00e9cnica compuesta por:<br>&#8211; Plano de ubicaci\u00f3n y localizaci\u00f3n seg\u00fan formato.<br>&#8211; Planos de arquitectura firmados por el profesional verificador.<\/li><li style=\"text-align: justify;\">Carta de seguridad de obra, firmada por un ingeniero civil colegiado.<\/li><li style=\"text-align: justify;\">Pago por inspecci\u00f3n t\u00e9cnica. S\/.<\/li><li style=\"text-align: justify;\">Tasa administrativa. S\/.<\/li><li style=\"text-align: justify;\">Derecho de revisi\u00f3n por la comisi\u00f3n.<\/li><li style=\"text-align: justify;\">Derecho de licencia.<br>De 0 hasta 3 000 m2.<br>De 3 000.1 m2 hasta 10 000 m2.<br>De 10 000.1 hasta 20 000 m2.<br>De 20 000.1 m2 hasta 30 000 m2<br>De 30 000.1 a m\u00e1 hasta un m\u00e1ximo de 100 UIT<br>Valor de la multa de construcci\u00f3n.<\/li><\/ol>\n\n\n<p style=\"color: rgb(68, 68, 68); text-align: center;\"><font size=\"3\"><strong>% UIT<\/strong><\/font><\/p><p><\/p>\n<p style=\"text-align: center; color: rgb(68, 68, 68); font-size: small;\">0.4348<\/p><p><\/p>\n<p style=\"text-align: center; color: rgb(68, 68, 68); font-size: small;\">0.7826<\/p><p><\/p>\n<p style=\"text-align: center; color: rgb(68, 68, 68); font-size: small;\">5.3044<\/p><p><\/p>\n<p style=\"text-align: center; color: rgb(68, 68, 68); font-size: small;\">1.5% VOC<br>1.4% VOC<br>1.3% VOC<br>1.2% VOC<br>1.1% VOC<br>10% VOC<\/p><p><\/p>\n\n\n<p style=\"color: rgb(68, 68, 68); font-size: small; text-align: center;\"><span style=\"font-size: medium;\"><strong>COSTO:<\/strong><\/span><br><\/p><p style=\"text-align: center;\"><span style=\"text-align: justify; color: rgb(68, 68, 68); font-size: small;\">Gratuito<br>M\u00e1ximo 1 UIT<\/span><\/p><p><\/p>\n<p style=\"color: rgb(68, 68, 68); font-size: small; text-align: center;\"><span style=\"text-align: justify;\">S\/. 20.00<\/span><br><\/p><p><\/p>\n<p style=\"color: rgb(68, 68, 68); font-size: small; text-align: center;\"><span style=\"text-align: justify;\">S\/. 36.60<\/span><br><\/p><p><\/p>\n<p style=\"color: rgb(68, 68, 68); font-size: small; text-align: center;\"><span style=\"text-align: justify;\">S\/. 244.00<\/span><br><\/p><p><\/p>\n\n\n\n\n\n\n\n\n<p style=\"color: rgb(68, 68, 68); text-align: justify;\"><strong>BASE LEGAL:<\/strong><\/p><ul style=\"color: rgb(68, 68, 68);\"><li style=\"text-align: justify;\"><font size=\"2\">Ley N\u00ba 27972 &#8211; Ley Org\u00e1nica de Municipalidades.<\/font><\/li><li style=\"text-align: justify;\"><span style=\"font-size: small;\">Ley N\u00ba 29090 &#8211; Ley de Regulaci\u00f3n de&nbsp; Habilitaciones Urbanas y de Edificaciones.<\/span><\/li><li style=\"text-align: justify;\"><span style=\"font-size: small;\">D.S. N\u00ba 024-2008-VIVIENDA. Reglamento de Ley 29090.<\/span><\/li><\/ul>\n\n\n<p style=\"color: rgb(68, 68, 68); font-size: small;\"><span style=\"font-size: medium;\"><strong>REQUISITOS:<\/strong><\/span><a href=\"https:\/\/drive.google.com\/file\/d\/1RBV66eHgI2yNvHLMKiOXz2Xr3kZ53XC_\/view?usp=sharing\"><br><\/a><\/p><ol style=\"font-size: small; color: rgb(68, 68, 68);\"><li style=\"text-align: justify;\"><a href=\"https:\/\/drive.google.com\/file\/d\/1RBV66eHgI2yNvHLMKiOXz2Xr3kZ53XC_\/view?usp=sharing\">Formulario \u00danico de Tr\u00e1mite (FUT)<\/a>. (Descargalo o solicitalo en mesa de partes)<\/li><li style=\"text-align: justify;\">Poderes de representaci\u00f3n de ser el caso.<\/li><li style=\"text-align: justify;\">Plano general de planta a escala 1:100 firmado por profesional habilitado.<\/li><li style=\"text-align: justify;\">Memoria descriptiva.<\/li><li style=\"text-align: justify;\">Metrado, presupuesto de obra y el cronograma de obra.<\/li><li style=\"text-align: justify;\">Pago por inspecci\u00f3n t\u00e9cnica. S\/.<\/li><li style=\"text-align: justify;\">Tasa administrativa (por una cabina telef\u00f3nica) S\/.<\/li><li style=\"text-align: justify;\">Ocupaci\u00f3n de v\u00eda p\u00fablico en \u00e1rea de uso p\u00fablico.<\/li><li style=\"text-align: justify;\">Copia de autoavaluo vigente.<\/li><\/ol>\n\n\n<p style=\"color: rgb(68, 68, 68); text-align: center;\"><font size=\"3\"><strong>% UIT<\/strong>:<\/font><\/p><p><\/p>\n<p style=\"color: rgb(68, 68, 68); font-size: small; text-align: center;\"><span style=\"text-align: justify;\">S\/. 5.00 x m2<\/span><br><\/p><p><\/p>\n\n\n<p style=\"color: rgb(68, 68, 68); font-size: small; text-align: center;\"><span style=\"font-size: medium;\"><strong>COSTO<\/strong><strong>:<\/strong><\/span><br><\/p><p style=\"text-align: center;\"><span style=\"text-align: justify; color: rgb(68, 68, 68); font-size: small;\">Gratuito<br>M\u00e1ximo 1 UIT<\/span><\/p><p><\/p>\n<p style=\"color: rgb(68, 68, 68); font-size: small; text-align: center;\"><span style=\"text-align: justify;\">S\/. 36.00<\/span><br><\/p><p><\/p>\n<p style=\"color: rgb(68, 68, 68); font-size: small; text-align: center;\"><span style=\"text-align: justify;\">S\/. 55.50<\/span><br><\/p><p><\/p>\n\n\n\n\n\n\n\n\n<p style=\"color: rgb(68, 68, 68); text-align: justify;\"><strong>BASE LEGAL:<\/strong><\/p><ul style=\"color: rgb(68, 68, 68);\"><li style=\"text-align: justify;\"><font size=\"2\">Ley N\u00ba 27972 &#8211; Ley Org\u00e1nica de Municipalidades.<\/font><\/li><\/ul>\n\n\n<p style=\"color: rgb(68, 68, 68); font-size: small;\"><span style=\"font-size: medium;\"><strong>REQUISITOS:<\/strong><\/span><a href=\"https:\/\/drive.google.com\/file\/d\/1RBV66eHgI2yNvHLMKiOXz2Xr3kZ53XC_\/view?usp=sharing\"><br><\/a><\/p><ol style=\"font-size: small; color: rgb(68, 68, 68);\"><li style=\"text-align: justify;\"><a href=\"https:\/\/drive.google.com\/file\/d\/1RBV66eHgI2yNvHLMKiOXz2Xr3kZ53XC_\/view?usp=sharing\">Formulario \u00danico de Tr\u00e1mite (FUT)<\/a>. (Descargalo o solicitalo en mesa de partes)<\/li><li style=\"text-align: justify;\">Copia literal de dominio expedida por el registro de predios, con una anticipaci\u00f3n no mayor a 30 d\u00edas naturales o certificado de posesi\u00f3n.<\/li><li style=\"text-align: justify;\">Poderes simple de representaci\u00f3n de ser el caso.&nbsp;<\/li><li style=\"text-align: justify;\">Pago por inspecci\u00f3n t\u00e9cnica. <strong>S\/.<\/strong><\/li><li style=\"text-align: justify;\">Tasa administrativa. <strong>S\/.<\/strong><\/li><li style=\"text-align: justify;\">Copia de autovaluo vigente.<\/li><\/ol>\n\n\n<p style=\"color: rgb(68, 68, 68); font-size: small; text-align: center;\"><span style=\"font-size: medium;\"><strong>COSTO:<\/strong><\/span><br><\/p><p style=\"text-align: center;\"><span style=\"text-align: justify; color: rgb(68, 68, 68); font-size: small;\">Gratuito<br>M\u00e1ximo 1 UIT<\/span><\/p><p><\/p>\n<p style=\"color: rgb(68, 68, 68); font-size: small; text-align: center;\"><span style=\"text-align: justify;\">S\/. 13.50<\/span><br><\/p><p><\/p>\n<p style=\"color: rgb(68, 68, 68); font-size: small; text-align: center;\"><span style=\"text-align: justify;\">S\/. 44.50<\/span><br><\/p><p><\/p>\n\n\n\n\n\n\n\n\n<p style=\"color: rgb(68, 68, 68); text-align: justify;\"><strong>BASE LEGAL:<\/strong><\/p><ul style=\"color: rgb(68, 68, 68);\"><li style=\"text-align: justify;\"><font size=\"2\">Ley N\u00ba 28294<\/font><\/li><li style=\"text-align: justify;\"><font size=\"2\">D.S N\u00ba 005-2006-JUS<\/font><\/li><li style=\"text-align: justify;\"><font size=\"2\">Res. Ministerial N\u00ba 10-93-JUS<br><br><strong>Tipo de Material:<\/strong><br>&#8211; Hormig\u00f3n m3<br>&#8211; Arena fina m3 (de 50 a&nbsp; 99.999 m3)<br><br><strong>Tipo de Material:<\/strong><br>&#8211; Hormig\u00f3n m3<br>&#8211; Arena fina m3 (de 100 a 499.99 m3)<br><br><strong>Tipo de Material:<\/strong><br>&#8211; Hormig\u00f3n m3<br>&#8211; Arena fina m3 (m\u00e1s de 500 m3)<br><br><strong>Tipo de Material:<\/strong><br>&#8211; Hormig\u00f3n m3&nbsp;<br>&#8211; Arena fina m3<\/font><\/li><\/ul>\n\n\n<p style=\"color: rgb(68, 68, 68); font-size: small;\"><span style=\"font-size: medium;\"><strong>REQUISITOS:<\/strong><\/span><a href=\"https:\/\/drive.google.com\/file\/d\/1RBV66eHgI2yNvHLMKiOXz2Xr3kZ53XC_\/view?usp=sharing\"><br><\/a><\/p><ol style=\"font-size: small; color: rgb(68, 68, 68);\"><li style=\"text-align: justify;\"><a href=\"https:\/\/drive.google.com\/file\/d\/1RBV66eHgI2yNvHLMKiOXz2Xr3kZ53XC_\/view?usp=sharing\">Formulario \u00danico de Tr\u00e1mite (FUT)<\/a>. (Descargalo o solicitalo en mesa de partes)<br>&#8211; N\u00ba de DNI del solicitante.<br>&#8211; Firma del solicitante<\/li><li style=\"text-align: justify;\">Expediente de extracci\u00f3n de materiales, debidamente firmado por las autoridades correspondientes.<\/li><li style=\"text-align: justify;\">En el caso de ser persona jur\u00eddica, presentar la vigencia de poder.<\/li><li style=\"text-align: justify;\">Determinaci\u00f3n del pago seg\u00fan la cantidad de material a extraer, expedida por la Gerencia de Infraestructura.<\/li><li style=\"text-align: justify;\">Recibo de pago.<br><br>Nota 1. Deber\u00e1 de realizar el pago de extracci\u00f3n de material seg\u00fan la cantidad.<\/li><\/ol>\n\n\n<p style=\"color: rgb(68, 68, 68); font-size: small; text-align: center;\"><span style=\"font-size: medium;\"><strong>COSTO:<\/strong><\/span><br><\/p><p style=\"text-align: center;\"><span style=\"text-align: justify; color: rgb(68, 68, 68); font-size: small;\">Gratuito<br>M\u00e1ximo 1 UIT<\/span><\/p><p><\/p>\n\n\n\n\n\n\n\n\n<p style=\"color: rgb(68, 68, 68); text-align: justify;\"><strong>BASE LEGAL:<\/strong><\/p><ul style=\"color: rgb(68, 68, 68);\"><li style=\"text-align: justify;\"><font size=\"2\">Ley N\u00ba 27972, Ley Org\u00e1nica de Municipalidades.<\/font><\/li><\/ul>\n\n\n<p style=\"color: rgb(68, 68, 68); font-size: small;\"><span style=\"font-size: medium;\"><strong>REQUISITOS:<\/strong><\/span><a href=\"https:\/\/drive.google.com\/file\/d\/1RBV66eHgI2yNvHLMKiOXz2Xr3kZ53XC_\/view?usp=sharing\"><br><\/a><\/p><ol style=\"font-size: small; color: rgb(68, 68, 68);\"><li style=\"text-align: justify;\"><a href=\"https:\/\/drive.google.com\/file\/d\/1RBV66eHgI2yNvHLMKiOXz2Xr3kZ53XC_\/view?usp=sharing\">Formulario \u00danico de Tr\u00e1mite (FUT)<\/a>. (Descargalo o solicitalo en mesa de partes)<br><\/li><li style=\"text-align: justify;\">Documento en el que conste la aprobaci\u00f3n de la instalaci\u00f3n por parte de la empresa concensionaria del servicio p\u00fablico.<\/li><li style=\"text-align: justify;\">Planos de ubicaci\u00f3n y proyecto firmados y sellados por ingeniero colegiado.<\/li><li style=\"text-align: justify;\">Memoria descriptiva, especificaciones t\u00e9cnicas, metrados y presupuesto.<\/li><li style=\"text-align: justify;\">Cronograma de obra.<\/li><li style=\"text-align: justify;\">Pago por inspecci\u00f3n t\u00e9cnica. <strong>S\/.<br><\/strong><\/li><li style=\"text-align: justify;\">Tasa administrativa por cada poste. <strong>S\/.<\/strong><\/li><\/ol>\n\n\n<p style=\"color: rgb(68, 68, 68); font-size: small; text-align: center;\"><span style=\"font-size: medium;\"><strong>COSTO:<\/strong><\/span><br><\/p><p style=\"text-align: center;\"><span style=\"text-align: justify; color: rgb(68, 68, 68); font-size: small;\">Gratuito<br>M\u00e1ximo 1 UIT<\/span><\/p><p><\/p>\n<p style=\"color: rgb(68, 68, 68); font-size: small; text-align: center;\"><span style=\"text-align: justify;\">S\/. 36.00<\/span><br><\/p><p><\/p>\n<p style=\"color: rgb(68, 68, 68); font-size: small; text-align: center;\"><span style=\"text-align: justify;\">S\/. 400.0<\/span><br><\/p><p><\/p>\n\n\n\n\n\n\n\n\n<p style=\"color: rgb(68, 68, 68); text-align: justify;\"><strong>BASE LEGAL:<\/strong><\/p><ul style=\"color: rgb(68, 68, 68);\"><li style=\"text-align: justify;\"><font size=\"2\">Decreto Legislativo N\u00ba 776<\/font><\/li><li style=\"text-align: justify;\"><font size=\"2\">Ley N\u00ba 27972, Ley Org\u00e1nica de Municipalidaes.<\/font><\/li><li style=\"text-align: justify;\"><font size=\"2\">Ley N\u00ba 27444<\/font><\/li><\/ul>\n\n\n<p style=\"color: rgb(68, 68, 68); font-size: small;\"><span style=\"font-size: medium;\"><strong>REQUISITOS:<\/strong><\/span><a href=\"https:\/\/drive.google.com\/file\/d\/1RBV66eHgI2yNvHLMKiOXz2Xr3kZ53XC_\/view?usp=sharing\"><br><\/a><\/p><ol style=\"font-size: small; color: rgb(68, 68, 68);\"><li style=\"text-align: justify;\"><a href=\"https:\/\/drive.google.com\/file\/d\/1RBV66eHgI2yNvHLMKiOXz2Xr3kZ53XC_\/view?usp=sharing\">Formulario \u00danico de Tr\u00e1mite (FUT)<\/a>. (Descargalo o solicitalo en mesa de partes)<br><\/li><li style=\"text-align: justify;\">Documentos sustentatorios que justifiquen el \u00e1rea a ocupar y el tiempo.<\/li><li style=\"text-align: justify;\">Pago por inspecci\u00f3n t\u00e9cnica. <strong>S\/.<\/strong><\/li><li style=\"text-align: justify;\">Tasa administrativa<\/li><li style=\"text-align: justify;\">Copia de autoavaluo vigente (de ser el caso)<br>&#8211; Con fines de permitir la edificaci\u00f3n. <strong>S\/.<\/strong><br>&#8211; Con fines diferentes a la edificaci\u00f3n. <strong>S\/.<\/strong><\/li><\/ol>\n\n\n<p style=\"color: rgb(68, 68, 68); font-size: small; text-align: center;\"><span style=\"font-size: medium;\"><strong>COSTO:<\/strong><\/span><br><\/p><p style=\"text-align: center;\"><span style=\"text-align: justify; color: rgb(68, 68, 68); font-size: small;\">Gratuito<br>M\u00e1ximo 1 UIT<\/span><\/p><p><\/p>\n<p style=\"color: rgb(68, 68, 68); font-size: small; text-align: center;\"><span style=\"text-align: justify;\">S\/. 40.00<\/span><br><\/p><p><\/p>\n<p style=\"color: rgb(68, 68, 68); font-size: small; text-align: center;\"><span style=\"text-align: justify;\">S\/. 60.00<\/span><br><\/p><p><\/p>\n<p style=\"color: rgb(68, 68, 68); font-size: small; text-align: center;\"><span style=\"text-align: justify;\">S\/. 80.00<\/span><br><\/p><p><\/p>\n\n\n\n\n\n\n\n\n<p style=\"color: rgb(68, 68, 68); text-align: justify;\"><strong>BASE LEGAL:<\/strong><\/p><ul style=\"color: rgb(68, 68, 68);\"><li style=\"text-align: justify;\"><font size=\"2\">Decreto Legislativo N\u00ba 776<\/font><\/li><li style=\"text-align: justify;\"><font size=\"2\">Ley N\u00ba 27972.<\/font><\/li><li style=\"text-align: justify;\"><font size=\"2\">Ley N\u00ba 27444 (Art. 44)<\/font><\/li><li style=\"text-align: justify;\"><font size=\"2\">Ley N\u00ba 28291 (Art. 14)<\/font><\/li><li style=\"text-align: justify;\"><font size=\"2\">D.S. N\u00ba 005-2006-JUS (Art. 39).<\/font><\/li><li style=\"text-align: justify;\"><font size=\"2\">Directiva 001-2006-DNCP\/CNC 17\/04\/06<\/font><\/li><li style=\"text-align: justify;\"><font size=\"2\">R.M. N\u00ba 155-2006-VIVIENDA (Art. 182)<\/font><\/li><\/ul>\n\n\n<p style=\"color: rgb(68, 68, 68); font-size: small;\"><span style=\"font-size: medium;\"><strong>REQUISITOS:<\/strong><\/span><a href=\"https:\/\/drive.google.com\/file\/d\/1RBV66eHgI2yNvHLMKiOXz2Xr3kZ53XC_\/view?usp=sharing\"><br><\/a><\/p><ol style=\"font-size: small; color: rgb(68, 68, 68);\"><li style=\"text-align: justify;\"><a href=\"https:\/\/drive.google.com\/file\/d\/1RBV66eHgI2yNvHLMKiOXz2Xr3kZ53XC_\/view?usp=sharing\">Formulario \u00danico de Tr\u00e1mite (FUT)<\/a>, conteniendo:. (Descargalo o solicitalo en mesa de partes)<br>&#8211; N\u00ba de DNI del solicitante<\/li><li style=\"text-align: justify;\">Copia literal de dominio o t\u00edtulo de propiedad vigente.<\/li><li style=\"text-align: justify;\">Croquis de ubicaci\u00f3n<\/li><li style=\"text-align: justify;\">Recibo de pago.<\/li><\/ol>\n\n\n<p style=\"color: rgb(68, 68, 68); font-size: small; text-align: center;\"><span style=\"font-size: medium;\"><strong>COSTO:<\/strong><\/span><br><\/p><p style=\"text-align: center;\"><span style=\"text-align: justify; color: rgb(68, 68, 68); font-size: small;\">Gratuito<br>M\u00e1ximo 1 UIT<\/span><\/p><p><\/p>\n<p style=\"color: rgb(68, 68, 68); font-size: small; text-align: center;\"><span style=\"text-align: justify;\">S\/. 38.50<\/span><br><\/p><p><\/p>\n\n\n\n\n\n\n\n\n<p style=\"color: rgb(68, 68, 68); text-align: justify;\"><strong>BASE LEGAL:<\/strong><\/p><ul style=\"color: rgb(68, 68, 68);\"><li style=\"text-align: justify;\"><span style=\"font-size: small;\">Ley N\u00ba 27972, Ley Org\u00e1nica de Municipalidades.<\/span><br><\/li><li style=\"text-align: justify;\"><font size=\"2\">Ley N\u00ba 27444 (Art. 44), Ley de Procedimiento Administrativo&nbsp; General.<\/font><\/li><\/ul>\n\n\n<p style=\"color: rgb(68, 68, 68); font-size: small;\"><span style=\"font-size: medium;\"><strong>REQUISITOS:<\/strong><\/span><a href=\"https:\/\/drive.google.com\/file\/d\/1RBV66eHgI2yNvHLMKiOXz2Xr3kZ53XC_\/view?usp=sharing\"><br><\/a><\/p><ol style=\"font-size: small; color: rgb(68, 68, 68);\"><li style=\"text-align: justify;\"><a href=\"https:\/\/drive.google.com\/file\/d\/1RBV66eHgI2yNvHLMKiOXz2Xr3kZ53XC_\/view?usp=sharing\">Formulario \u00danico de Tr\u00e1mite (FUT)<\/a>&nbsp;&#8211; (Descargalo o solicitalo en mesa de partes)<\/li><li style=\"text-align: justify;\">Planos de arquitectura de plantas, cortes y elevaciones a escala conveniente (1:75 o 1:50) firmado y sellado por el profesional responsable y propietario.<\/li><li style=\"text-align: justify;\">Plano de especialidades (estructura, instalaci\u00f3n el\u00e9ctrica, mec\u00e1nicas, electromec\u00e1nicas, especiales con tecnolog\u00eda de \u00faltima generaci\u00f3n), firmados por el ingeniero proyectista y propietario a escala conveniente; Memoria descriptiva de cada una de las especialidades presentadas, firmadas por los proyectistas responsables.<\/li><li style=\"text-align: justify;\">Declaraci\u00f3n Jurada suscrita por el profesional responsable de la obra y el propietario se\u00f1alando que la obra reune las condiciones de seguridad interna y externa, que no causa ruidos molestos, ni causar\u00e1 interferencias radiales, telef\u00f3nicas ni de televisi\u00f3n.<\/li><li style=\"text-align: justify;\">Autorizaci\u00f3n expedida por el Ministerio de Transportes y Comunicaciones.<\/li><li style=\"text-align: justify;\">P\u00f3liza de seguro contra todo riesgo para los trabajadores que ejecutar\u00e1n la instalaci\u00f3n.<\/li><li style=\"text-align: justify;\">Boleta de inspecci\u00f3n de Defensa Civil.<\/li><li style=\"text-align: justify;\">Pago por inspecci\u00f3n t\u00e9cnica. <strong>S\/.<\/strong><\/li><li style=\"text-align: justify;\">Copia de autoavaluo vigente (de ser el caso)<\/li><li style=\"text-align: justify;\">Tasa administrativa por cada antena (De ser procedente iniciar los tr\u00e1mites). <strong>S\/.<\/strong><\/li><\/ol>\n\n\n<p style=\"color: rgb(68, 68, 68); font-size: small; text-align: center;\"><span style=\"font-size: medium;\"><strong>COSTO:<\/strong><\/span><br><\/p><p style=\"text-align: center;\"><span style=\"text-align: justify; color: rgb(68, 68, 68); font-size: small;\">Gratuito<br>M\u00e1ximo 1 UIT<\/span><\/p><p><\/p>\n<p style=\"color: rgb(68, 68, 68); font-size: small; text-align: center;\"><span style=\"text-align: justify;\">S\/. 40.00<\/span><br><\/p><p><\/p>\n<p style=\"color: rgb(68, 68, 68); font-size: small; text-align: center;\"><span style=\"text-align: justify;\">S\/. 592.00<\/span><br><\/p><p><\/p>\n\n\n\n\n\n\n\n\n\n\n\n\n<p style=\"background-color: rgb(102, 185, 102); text-align: center; color: rgb(255, 255, 255);\"><strong>1<\/strong><\/p>\n\n\n<p style=\"text-align: center; color: rgb(68, 68, 68); font-size: large;\"><a href=\"https:\/\/munimarianodamasoberaun.gob.pe\/home\/tupa-catastro-2\/\">2<\/a><\/p>\n\n\n<p style=\"text-align: center; color: rgb(68, 68, 68); font-size: large;\"><a href=\"https:\/\/munimarianodamasoberaun.gob.pe\/home\/tupa-catastro-3\/\">3<\/a><\/p>\n\n\n<p style=\"text-align: center; color: rgb(68, 68, 68); font-size: large;\"><a href=\"https:\/\/munimarianodamasoberaun.gob.pe\/home\/tupa-catastro-4\/\">4<\/a><\/p>\n\n\n<p style=\"text-align: center; color: rgb(68, 68, 68); font-size: large;\"><a href=\"https:\/\/munimarianodamasoberaun.gob.pe\/home\/tupa-catastro-5\/\">5<\/a><\/p>\n\n\n<p style=\"text-align: left; color: rgb(68, 68, 68); font-size: large;\"><a href=\"https:\/\/munimarianodamasoberaun.gob.pe\/home\/tupa-catastro-2\/\">Siguiente<\/a><\/p>\n\n\n\n\n\n\n\n\n\n\n\n<iframe loading=\"lazy\" src=\"https:\/\/www.facebook.com\/plugins\/page.php?href=https%3A%2F%2Fwww.facebook.com%2Fmunipalmasoficial&amp;tabs=timeline&amp;width=306&amp;height=1500&amp;small_header=false&amp;adapt_container_width=true&amp;hide_cover=false&amp;show_facepile=true&amp;appId=181184886316165\" width=\"306\" height=\"700\" style=\"border:none;overflow:hidden\" scrolling=\"no\" frameborder=\"0\" allowfullscreen=\"true\" allow=\"autoplay; clipboard-write; encrypted-media; picture-in-picture; web-share\"><\/iframe>\n\n\n<p>Lorem Ipsum has been the industry&#8217;s standard dummy text ever since the 1500s.<\/p>\n\n\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"pagelayer_contact_templates":[],"_pagelayer_content":"","footnotes":""},"class_list":["post-2022","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/munimarianodamasoberaun.gob.pe\/home\/wp-json\/wp\/v2\/pages\/2022","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/munimarianodamasoberaun.gob.pe\/home\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/munimarianodamasoberaun.gob.pe\/home\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/munimarianodamasoberaun.gob.pe\/home\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/munimarianodamasoberaun.gob.pe\/home\/wp-json\/wp\/v2\/comments?post=2022"}],"version-history":[{"count":135,"href":"https:\/\/munimarianodamasoberaun.gob.pe\/home\/wp-json\/wp\/v2\/pages\/2022\/revisions"}],"predecessor-version":[{"id":2597,"href":"https:\/\/munimarianodamasoberaun.gob.pe\/home\/wp-json\/wp\/v2\/pages\/2022\/revisions\/2597"}],"wp:attachment":[{"href":"https:\/\/munimarianodamasoberaun.gob.pe\/home\/wp-json\/wp\/v2\/media?parent=2022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}